{"id":15559,"date":"2023-07-10T23:43:47","date_gmt":"2023-07-11T03:43:47","guid":{"rendered":"https:\/\/www.captionmagazine.org\/?p=15559"},"modified":"2023-07-11T18:34:26","modified_gmt":"2023-07-11T22:34:26","slug":"photoescuela-cabanillas-del-campo-espana","status":"publish","type":"post","link":"https:\/\/www.captionmagazine.org\/en\/nuevas-miradas\/photoescuela-cabanillas-del-campo-espana","title":{"rendered":"PhotoEscuela Cabanillas del Campo, Espa\u00f1a"},"content":{"rendered":"<h3>La PhotoEscuela ya cuenta con ocho a\u00f1os de trayectoria. Inicialmente lo que ser\u00eda un peque\u00f1o taller de fotograf\u00eda en Cabanillas del Campo, Guadalajara, r\u00e1pidamente se consolid\u00f3 y la idea fue cogiendo forma. El humilde taller se convertir\u00eda en una escuela de fotograf\u00eda peque\u00f1a, pero con grandes sue\u00f1os.<\/h3>\n<p><strong>Esta iniciativa nace de una idea del fot\u00f3grafo Nacho Izquierdo y se estructura b\u00e1sicamente en dos grupos: un nivel de iniciaci\u00f3n y otro de avanzados, con un grupo de 15 alumnos por clase. El m\u00e9todo de ense\u00f1anza se basa en una fuerte formaci\u00f3n te\u00f3rica, pero tambi\u00e9n pr\u00e1ctica, donde los alumnos trabajan en base a proyectos personales, adem\u00e1s de participar de m\u00e1ster class con reconocidos fot\u00f3grafos. Asimismo, realizan pr\u00e1cticas en estudio con iluminaci\u00f3n de flash y desarrollan diversos tipos de reportajes, orientados por el profesorado. La idea es que cada uno de ellos pueda experimentar en los distintos campos de la fotograf\u00eda, para finalmente decantarse por un estilo m\u00e1s personal.<\/strong><br \/>\n<strong>Aqu\u00ed, damos cuenta de esos avances.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link\" style=\"border-radius: 10px;\" href=\"https:\/\/www.captionmagazine.org\/papel-digital-n22#page104\" rel=\"noreferrer noopener\">Lee este art\u00edculo en papel digital<\/a><\/div>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Cercan\u00edas<\/strong><br \/>\nPor Esperanza Torres<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/espe1.964\/\" target=\"_blank\" rel=\"noopener\">@espe1.964<\/a><\/p>\n<p>Cuando monto en el tren de cercan\u00edas mi mirada siempre es en blanco y negro. Hay d\u00edas en que la niebla difumina a los viajeros en los andenes haciendo desaparecer sus almas. En otros, el sol aparece entre las nubes o se esconde detr\u00e1s de los edificios llegando a Atocha. Desde las ventanillas desgastadas del tren, se cuelan las viejas f\u00e1bricas, la noria de las fiestas de un pueblo cercano, un hotel solitario en el horizonte, un pasajero duerme, mientras al fondo un cielo que invita a so\u00f1ar, huele a melancol\u00eda infinita y al cansancio de un largo d\u00eda de trabajo. En Atocha, una pareja iluminada bajo un tragaluz susurra silenciosa una oraci\u00f3n atea por las v\u00edctimas del 11M. El tren est\u00e1 repleto de historias, repleto de paisajes.<\/p>\n<div id='gallery-1' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-15568\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5466-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-15568'>\n\t\t\t\t\u00a9 Esperanza Torres\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-15566\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/IMG_5429-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-15566'>\n\t\t\t\t\u00a9 Esperanza Torres\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-15564\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Cercanias_Esperanza-Torrez_01-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-15564'>\n\t\t\t\t\u00a9 Esperanza Torres\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-15562\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7822-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-15562'>\n\t\t\t\t\u00a9 Esperanza Torres\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<p><strong>Calma<\/strong><br \/>\nPor Carmen Melero<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/_carmen_photo\/\" target=\"_blank\" rel=\"noopener\">@_carmen_photo<\/a><\/p>\n<p>La calma es como una brisa suave que acaricia nuestro ser, llev\u00e1ndose consigo las preocupaciones y el estr\u00e9s que nos envuelven. Es como un lago en un d\u00eda despejado, reflejando la belleza del paisaje sin perturbaci\u00f3n alguna. Es la armon\u00eda entre el moverse y el reposar, una danza pausada que invita a la introspecci\u00f3n y a la conexi\u00f3n con uno mismo. Buscar la calma no implica huir de la realidad, sino m\u00e1s bien encontrar un equilibrio interno que nos permita enfrentarla de manera m\u00e1s eficaz. Nos ayuda a recuperar la energ\u00eda y la tranquilidad necesarias para ser la mejor versi\u00f3n de nosotros mismos.<\/p>\n<div id='gallery-2' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-15570\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_7733-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-15570'>\n\t\t\t\t\u00a9 Carmen Melero\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-15572\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8005-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-15572'>\n\t\t\t\t\u00a9 Carmen Melero\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-15574\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8007-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-15574'>\n\t\t\t\t\u00a9 Carmen Melero\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-15576\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_8008-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-15576'>\n\t\t\t\t\u00a9 Carmen Melero\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<p><strong>Botargas<\/strong><br \/>\nPor Alicia Somolinos y Julio Herranz<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/alicia23somolinos\" target=\"_blank\" rel=\"noopener\">@alicia23somolinos<\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/julio.herranz\/\" target=\"_blank\" rel=\"noopener\">@julio.herranz<\/a><\/p>\n<p>Botargas, mascaritas, diablos, vaquillones, mojigangas. Todo esto forma parte de nuestras m\u00e1s antiguas tradiciones de origen pagano. Algunos peque\u00f1os pueblos de Guadalajara recuperan y mantienen estas celebraciones, ayudando a conservar el folklore popular, a la vez que transmiten a las nuevas generaciones nuestras costumbres m\u00e1s ancestrales.<\/p>\n<div id='gallery-3' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-15578\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP3555-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-15578'>\n\t\t\t\t\u00a9 Alicia Somolinos de Pedro\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-15582\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP5127-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-15582'>\n\t\t\t\t\u00a9 Alicia Somolinos de Pedro\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-15580\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/ASP4397-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-15580'>\n\t\t\t\tAlicia Somolinos de Pedro\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-15584\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/JHE5337-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-15584'>\n\t\t\t\t\u00a9 Julio Herranz\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<p><strong>Gente en Museos<\/strong><br \/>\nPor Fran Montes<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/paquiro60\/\" target=\"_blank\" rel=\"noopener\">@paquiro60<\/a><\/p>\n<p>Los museos albergan sorpresas que ni sospech\u00e1bamos que estuvieran en sus salas. Distracci\u00f3n, admiraci\u00f3n, bostezos, sorpresas, aprendizaje, entretenimiento, literatura trasmutada en materia, trabajo, curiosidad, ense\u00f1anza, destreza, rid\u00edculo, aburrimiento, amistad, juegos, fatiga, t\u00e9cnica, descanso, encuentros, prisa, tranquilidad. Todo eso lo podemos encontrar tambi\u00e9n en los museos. Sus visitantes forman una multitud variopinta que genera un espect\u00e1culo humano con una din\u00e1mica propia tan atractiva como las obras que albergan. Basta con prestar atenci\u00f3n y mirar con detenimiento. All\u00ed est\u00e1, ante nuestros ojos.<\/p>\n<div id='gallery-4' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-15588\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0017-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-15588'>\n\t\t\t\t\u00a9 Fran Montes\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-15590\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-13-Gente-en-museos-0024-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-15590'>\n\t\t\t\tFran Montes\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-15592\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-03-27-Gente-en-museos-0026-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-15592'>\n\t\t\t\tFran Montes\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-15594\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/2023-02-09-Gente-en-museos-0011-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-15594'>\n\t\t\t\tFran Montes\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<p><strong>Callejeando<\/strong><br \/>\nPor Paco Vizca\u00edno<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/pacovizcainogarcia\/\" target=\"_blank\" rel=\"noopener\">@pacovizcainogarcia<\/a><\/p>\n<p>Cazador: Dicho de una persona que caza por oficio o por diversi\u00f3n, as\u00ed me siento cuando cojo mi c\u00e1mara, un cazador de im\u00e1genes y no por oficio sino por diversi\u00f3n. Callejeando es patear Madrid sin rumbo fijo, sin saber lo que vas a encontrarte en la siguiente calle, es mirar, es observar a la gente, es esperar y a la vez desesperar, es tener suerte y cazar la foto a la vuelta de una esquina, es hacer mil fotos, llegar a casa y no quedarte con ninguna. Callejeando es andar y andar hasta que te duelen los pies y a\u00fan as\u00ed sigues andando so\u00f1ando con la foto perfecta o simplemente con la foto que te guste. Callejeando es ser un voyeur, espiar los balcones buscando alguna escena, fisgar a trav\u00e9s de los cristales de alg\u00fan bar, de alg\u00fan portal, es cruce de miradas, es robar un gesto, una acci\u00f3n, un rostro, un reflejo. Callejeando es La PhotoEscuela, es Nacho Izquierdo, nuestro profesor y amigo que a\u00f1o tras a\u00f1o nos ense\u00f1a a ser manuales y no autom\u00e1ticos, nos muestra el trabajo de los buenos fot\u00f3grafos y nos gu\u00eda por los m\u00faltiples caminos que tiene este gran arte que es la Fotograf\u00eda.<\/p>\n<div id='gallery-5' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-5-15598\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/DSC08494-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-15598'>\n\t\t\t\t\u00a9 Paco Vizca\u00edno\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-5-15596\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Voyeur-de-Ciudad-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-15596'>\n\t\t\t\t\u00a9 Paco Vizca\u00edno\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-5-15600\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/RS8725_Bostezando-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-15600'>\n\t\t\t\t\u00a9 Paco Vizca\u00edno\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-5-15602\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/Un-Senal-dios-mio-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-15602'>\n\t\t\t\t\u00a9 Paco Vizca\u00edno\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<hr \/>\n<p><strong>Los Ojos de Londres<\/strong><br \/>\nPor Victoria \u00c1lvarez<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/vickyalgm_foto\/\" target=\"_blank\" rel=\"noopener\">@vickyalgm_foto<\/a><\/p>\n<p>Esta tarea es llevada a cabo en la ciudad de Londres, m\u00e1s centrado en Camden Town. Siendo mi primer trabajo sobre foto callejera, he tenido de inspiraci\u00f3n de la est\u00e9tica de las pel\u00edculas adolescentes americanas que m\u00e1s me gustan. Intento darle una visi\u00f3n cinematogr\u00e1fica a los planos y colores de las fotograf\u00edas, con la intenci\u00f3n de alejarme del encuadre o enfoque \u201cperfecto\u201d.<\/p>\n<div id='gallery-6' class='gallery galleryid-15559 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-6-15604\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5682-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-15604'>\n\t\t\t\t\u00a9 Victoria \u00c1lvarez\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-6-15606\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5752-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-15606'>\n\t\t\t\t\u00a9 Victoria \u00c1lvarez\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-6-15608\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5764-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-15608'>\n\t\t\t\t\u00a9 Victoria \u00c1lvarez\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836-160x160.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-6-15610\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836-160x160.jpg 160w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836-90x90.jpg 90w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836-20x19.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2023\/07\/MG_5836-100x100.jpg 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-15610'>\n\t\t\t\t\u00a9 Victoria \u00c1lvarez\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Sitios web:<\/strong><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/photoescuela_cabanillas\/#\" target=\"_blank\" rel=\"noopener\">@photoescuela_cabanillas<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La PhotoEscuela ya cuenta con ocho a\u00f1os de trayectoria. Inicialmente lo que ser\u00eda un peque\u00f1o taller de fotograf\u00eda en Cabanillas del Campo, Guadalajara, r\u00e1pidamente se consolid\u00f3 y la idea fue cogiendo forma. El humilde taller se convertir\u00eda en una escuela de fotograf\u00eda peque\u00f1a, pero con grandes sue\u00f1os. Esta iniciativa nace de una idea del fot\u00f3grafo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":15607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[816],"tags":[905,985],"thb-sponsors":[],"class_list":["post-15559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuevas-miradas","tag-escuelas-2","tag-n22"],"_links":{"self":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/posts\/15559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/comments?post=15559"}],"version-history":[{"count":4,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/posts\/15559\/revisions"}],"predecessor-version":[{"id":15664,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/posts\/15559\/revisions\/15664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/media\/15607"}],"wp:attachment":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/media?parent=15559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/categories?post=15559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/tags?post=15559"},{"taxonomy":"thb-sponsors","embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/thb-sponsors?post=15559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}