{"id":10192,"date":"2022-07-07T19:50:41","date_gmt":"2022-07-07T23:50:41","guid":{"rendered":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original.jpg"},"modified":"2022-08-24T19:03:59","modified_gmt":"2022-08-24T23:03:59","slug":"rs5417_insomnia-010-original-2","status":"inherit","type":"attachment","link":"https:\/\/www.captionmagazine.org\/en\/new-perspectives\/pic-a-school-madrid\/attachment\/rs5417_insomnia-010-original-2","title":{"rendered":"RS5417_Insomnia 010-original"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"giftcard-category":[],"class_list":["post-10192","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original.jpg' class=\"mfp-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"463\" src=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-640x463.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-640x463.jpg 640w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-600x434.jpg 600w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-370x267.jpg 370w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-185x134.jpg 185w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x14.jpg 20w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-400x289.jpg 400w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-300x217.jpg 300w, https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-66x48.jpg 66w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1084,"file":"2022\/07\/RS5417_Insomnia-010-original.jpg","filesize":968626,"sizes":{"woocommerce_thumbnail":{"file":"RS5417_Insomnia-010-original-300x300.jpg","width":300,"height":300,"filesize":33687,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-300x217.jpg"},"woocommerce_gallery_thumbnail":{"file":"RS5417_Insomnia-010-original-100x100.jpg","width":100,"height":100,"filesize":20006,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-100x100.jpg"},"woocommerce_single":{"file":"RS5417_Insomnia-010-original-600x434.jpg","width":600,"height":434,"filesize":53928,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-600x434.jpg"},"medium":{"file":"RS5417_Insomnia-010-original-640x463.jpg","width":640,"height":463,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-640x463.jpg"},"large":{"file":"RS5417_Insomnia-010-original-1280x925.jpg","width":1280,"height":925,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-1280x925.jpg"},"thumbnail":{"file":"RS5417_Insomnia-010-original-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-160x160.jpg"},"medium_large":{"file":"RS5417_Insomnia-010-original-768x555.jpg","width":768,"height":555,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-768x555.jpg"},"post-thumbnail":{"file":"RS5417_Insomnia-010-original-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-180x180.jpg"},"theissue-thumbnail":{"file":"RS5417_Insomnia-010-original-90x90.jpg","width":90,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-90x90.jpg"},"theissue-square":{"file":"RS5417_Insomnia-010-original-370x355.jpg","width":370,"height":355,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-370x355.jpg"},"theissue-squaresmall":{"file":"RS5417_Insomnia-010-original-370x300.jpg","width":370,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-370x300.jpg"},"theissue-rectangle":{"file":"RS5417_Insomnia-010-original-370x230.jpg","width":370,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-370x230.jpg"},"theissue-masonry":{"file":"RS5417_Insomnia-010-original-370x267.jpg","width":370,"height":267,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-370x267.jpg"},"theissue-full":{"file":"RS5417_Insomnia-010-original-800x578.jpg","width":800,"height":578,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-800x578.jpg"},"theissue-thumbnail-small":{"file":"RS5417_Insomnia-010-original-45x180.jpg","width":45,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-45x180.jpg"},"theissue-thumbnail-x2":{"file":"RS5417_Insomnia-010-original-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-180x180.jpg"},"theissue-thumbnail-mini":{"file":"RS5417_Insomnia-010-original-20x20.jpg","width":20,"height":20,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x20.jpg"},"theissue-square-small":{"file":"RS5417_Insomnia-010-original-185x710.jpg","width":185,"height":710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-185x710.jpg"},"theissue-square-x2":{"file":"RS5417_Insomnia-010-original-740x710.jpg","width":740,"height":710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-740x710.jpg"},"theissue-square-x3":{"file":"RS5417_Insomnia-010-original-1110x1065.jpg","width":1110,"height":1065,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-1110x1065.jpg"},"theissue-square-mini":{"file":"RS5417_Insomnia-010-original-20x19.jpg","width":20,"height":19,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x19.jpg"},"theissue-squaresmall-small":{"file":"RS5417_Insomnia-010-original-185x600.jpg","width":185,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-185x600.jpg"},"theissue-squaresmall-x2":{"file":"RS5417_Insomnia-010-original-740x600.jpg","width":740,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-740x600.jpg"},"theissue-squaresmall-mini":{"file":"RS5417_Insomnia-010-original-20x16.jpg","width":20,"height":16,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x16.jpg"},"theissue-rectangle-small":{"file":"RS5417_Insomnia-010-original-185x460.jpg","width":185,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-185x460.jpg"},"theissue-rectangle-x2":{"file":"RS5417_Insomnia-010-original-740x460.jpg","width":740,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-740x460.jpg"},"theissue-rectangle-x3":{"file":"RS5417_Insomnia-010-original-1110x690.jpg","width":1110,"height":690,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-1110x690.jpg"},"theissue-rectangle-mini":{"file":"RS5417_Insomnia-010-original-20x12.jpg","width":20,"height":12,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x12.jpg"},"theissue-masonry-small":{"file":"RS5417_Insomnia-010-original-185x134.jpg","width":185,"height":134,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-185x134.jpg"},"theissue-masonry-x2":{"file":"RS5417_Insomnia-010-original-740x535.jpg","width":740,"height":535,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-740x535.jpg"},"theissue-masonry-mini":{"file":"RS5417_Insomnia-010-original-20x14.jpg","width":20,"height":14,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x14.jpg"},"theissue-full-small":{"file":"RS5417_Insomnia-010-original-400x289.jpg","width":400,"height":289,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-400x289.jpg"},"theissue-full-mini":{"file":"RS5417_Insomnia-010-original-20x14.jpg","width":20,"height":14,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-20x14.jpg"},"awsm_team":{"file":"RS5417_Insomnia-010-original-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-500x500.jpg"},"wopgld-frame-image":{"file":"RS5417_Insomnia-010-original-478x300.jpg","width":478,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-478x300.jpg"},"shop_catalog":{"file":"RS5417_Insomnia-010-original-300x217.jpg","width":300,"height":217,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-300x217.jpg"},"shop_single":{"file":"RS5417_Insomnia-010-original-600x434.jpg","width":600,"height":434,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-600x434.jpg"},"shop_thumbnail":{"file":"RS5417_Insomnia-010-original-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-100x100.jpg"},"thb-sponsor-x2":{"file":"RS5417_Insomnia-010-original-66x48.jpg","width":66,"height":48,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original-66x48.jpg"},"full":{"file":"RS5417_Insomnia-010-original.jpg","width":1500,"height":1084,"mime_type":"image\/jpeg","source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original.jpg"}},"image_meta":{"aperture":"2.8","credit":"Silvia del Barrio","camera":"NIKON D750","caption":"","created_timestamp":"1556242231","copyright":"Silvia del Barrio","focal_length":"30","iso":"800","shutter_speed":"0.0125","title":"","orientation":"1","keywords":[]}},"post":10595,"source_url":"https:\/\/www.captionmagazine.org\/wp-content\/uploads\/2022\/07\/RS5417_Insomnia-010-original.jpg","_links":{"self":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/media\/10192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/comments?post=10192"}],"wp:term":[{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.captionmagazine.org\/en\/wp-json\/wp\/v2\/giftcard-category?post=10192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}